{"id":247,"date":"2013-04-04T09:38:55","date_gmt":"2013-04-04T08:38:55","guid":{"rendered":"http:\/\/www.tutele.net\/forotpa\/?p=247"},"modified":"2013-04-04T09:38:55","modified_gmt":"2013-04-04T08:38:55","slug":"la-adjudicataria-de-los-informativos-de-tpa-en-preconcurso-de-acreedores","status":"publish","type":"post","link":"https:\/\/www.tutele.net\/forotpa\/2013\/04\/04\/la-adjudicataria-de-los-informativos-de-tpa-en-preconcurso-de-acreedores\/","title":{"rendered":"La adjudicataria de los informativos de TPA, en preconcurso de acreedores"},"content":{"rendered":"<p>Anunci\u00e1bamos hace <a title=\"VAV en venta\" href=\"https:\/\/www.tutele.net\/forotpa\/2013\/04\/02\/vav-adjudicataria-de-los-informativos-de-tpa-en-venta\/\" target=\"_blank\">dos d\u00edas que VAV estaba en venta<\/a> y hab\u00eda sido ofrecida a varias empresas del sector. Ese d\u00eda tambi\u00e9n ten\u00edamos noticias de que VAV podr\u00eda haber solicitado un preconcurso de acreedores, pero no lo pudimos confirmar.<\/p>\n<p>Hoy <a title=\"El Confidencial Digital VAV\" href=\"http:\/\/elconfidencialdigital.com\/medios\/082672\/las-grandes-productoras-de-servicios-audiovisuales-se-quejan-al-gobierno-de-asturias-por-adjudicar-el-contrato-de-informativos-a-una-empresa-en-preconcurso-de-acreedores\" target=\"_blank\">El Confidencial Digital <\/a>anuncia que las grandes productoras han mostrado su malestar al Principado de Asturias y \u00ab<em>se quejan de que se trata de\u00a0una compa\u00f1\u00eda en preconcurso de acreedores\u00bb.<\/em><\/p>\n<p><script type=\"text\/javascript\">\/\/ <![CDATA[\nsas_pageid='9787\/72272';\t\/\/ P\u00e1gina : tutele\/others\nsas_formatid=4258;\t\t\/\/ Formato : 468x60 468x60\nsas_target='';\t\t\t\/\/ Targeting\nSmartAdServer(sas_pageid,sas_formatid,sas_target);\n\/\/ ]]><\/script><\/p>\n<p><noscript><br \/>\n<a href=\"http:\/\/reachandrich.antevenio.com\/call\/pubjumpi\/9787\/72272\/4258\/S\/[timestamp]\/?\"><br \/>\n<img decoding=\"async\" src=\"http:\/\/reachandrich.antevenio.com\/call\/pubi\/9787\/72272\/4258\/S\/[timestamp]\/?\" border=\"0\" alt=\"\" \/><\/a><br \/>\n<\/noscript><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anunci\u00e1bamos hace dos d\u00edas que VAV estaba en venta y hab\u00eda sido ofrecida a varias empresas del sector. Ese d\u00eda tambi\u00e9n ten\u00edamos noticias de que VAV podr\u00eda haber solicitado un preconcurso de acreedores, pero no lo pudimos confirmar. Hoy El Confidencial Digital anuncia que las grandes productoras han mostrado su malestar al Principado de Asturias &hellip; <a href=\"https:\/\/www.tutele.net\/forotpa\/2013\/04\/04\/la-adjudicataria-de-los-informativos-de-tpa-en-preconcurso-de-acreedores\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa adjudicataria de los informativos de TPA, en preconcurso de acreedores\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,6],"tags":[4,15,44],"_links":{"self":[{"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/posts\/247"}],"collection":[{"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/comments?post=247"}],"version-history":[{"count":0,"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/posts\/247\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/media?parent=247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/categories?post=247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tutele.net\/forotpa\/wp-json\/wp\/v2\/tags?post=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}